{"id":5037,"count":33,"description":"","link":"https:\/\/opentalk.iit.it\/en\/category\/eventi-en\/","name":"Eventi","slug":"eventi-en","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eventi Archivi - Talk iit<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/opentalk.iit.it\/en\/category\/eventi-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eventi Archivi - Talk iit\" \/>\n<meta property=\"og:url\" content=\"https:\/\/opentalk.iit.it\/en\/category\/eventi-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Talk iit\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/opentalk.iit.it\\\/en\\\/category\\\/eventi-en\\\/\",\"url\":\"https:\\\/\\\/opentalk.iit.it\\\/en\\\/category\\\/eventi-en\\\/\",\"name\":\"Eventi Archivi - Talk iit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/opentalk.iit.it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/opentalk.iit.it\\\/en\\\/category\\\/eventi-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/opentalk.iit.it\\\/en\\\/category\\\/eventi-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/opentalk.iit.it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eventi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/opentalk.iit.it\\\/#website\",\"url\":\"https:\\\/\\\/opentalk.iit.it\\\/\",\"name\":\"Talk iit\",\"description\":\"IITalk\",\"publisher\":{\"@id\":\"https:\\\/\\\/opentalk.iit.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/opentalk.iit.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/opentalk.iit.it\\\/#organization\",\"name\":\"Talk iit\",\"url\":\"https:\\\/\\\/opentalk.iit.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/opentalk.iit.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/opentalk.iit.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/opentalk-logo.png\",\"contentUrl\":\"https:\\\/\\\/opentalk.iit.it\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/opentalk-logo.png\",\"width\":802,\"height\":265,\"caption\":\"Talk iit\"},\"image\":{\"@id\":\"https:\\\/\\\/opentalk.iit.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eventi Archivi - Talk iit","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/opentalk.iit.it\/en\/category\/eventi-en\/","og_locale":"en_US","og_type":"article","og_title":"Eventi Archivi - Talk iit","og_url":"https:\/\/opentalk.iit.it\/en\/category\/eventi-en\/","og_site_name":"Talk iit","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/opentalk.iit.it\/en\/category\/eventi-en\/","url":"https:\/\/opentalk.iit.it\/en\/category\/eventi-en\/","name":"Eventi Archivi - Talk iit","isPartOf":{"@id":"https:\/\/opentalk.iit.it\/#website"},"breadcrumb":{"@id":"https:\/\/opentalk.iit.it\/en\/category\/eventi-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/opentalk.iit.it\/en\/category\/eventi-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/opentalk.iit.it\/"},{"@type":"ListItem","position":2,"name":"Eventi"}]},{"@type":"WebSite","@id":"https:\/\/opentalk.iit.it\/#website","url":"https:\/\/opentalk.iit.it\/","name":"Talk iit","description":"IITalk","publisher":{"@id":"https:\/\/opentalk.iit.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/opentalk.iit.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/opentalk.iit.it\/#organization","name":"Talk iit","url":"https:\/\/opentalk.iit.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/opentalk.iit.it\/#\/schema\/logo\/image\/","url":"https:\/\/opentalk.iit.it\/wp-content\/uploads\/2023\/04\/opentalk-logo.png","contentUrl":"https:\/\/opentalk.iit.it\/wp-content\/uploads\/2023\/04\/opentalk-logo.png","width":802,"height":265,"caption":"Talk iit"},"image":{"@id":"https:\/\/opentalk.iit.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/opentalk.iit.it\/en\/wp-json\/wp\/v2\/categories\/5037","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/opentalk.iit.it\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/opentalk.iit.it\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/opentalk.iit.it\/en\/wp-json\/wp\/v2\/posts?categories=5037"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}